{"id":10754,"date":"2022-11-15T07:00:00","date_gmt":"2022-11-15T05:00:00","guid":{"rendered":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?p=10754"},"modified":"2025-07-30T15:24:15","modified_gmt":"2025-07-30T13:24:15","slug":"hamletiano-hamletiana","status":"publish","type":"post","link":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/","title":{"rendered":"hamletiano, hamletiana <em>adj.<\/em>"},"content":{"rendered":"\n<p>William Shakespeare (Stratford-on-Avon, 1564-1616) es conocido por su faceta como poeta, dramaturgo y actor, y es considerado uno de los autores m\u00e1s c\u00e9lebres e influyentes de la literatura inglesa y universal. Sin embargo, no es tan conocido por su faceta de ne\u00f3logo. De las m\u00e1s de 1600 palabras que se le atribuyen, algunas fueron creadas por \u00e9l y otras simplemente las populariz\u00f3, pues, si bien se utilizaban, no se hab\u00edan plasmado nunca en papel. Acu\u00f1\u00f3 palabras como, por ejemplo, <em>gossip<\/em> \u2018chismorrear\u2019, que aparece en <em>La comedia de las equivocaciones<\/em>, <em>lonely<\/em> \u2018solo, -la\u2019 (<em>Coriolano<\/em>), y <em>bedroom<\/em> \u2018dormitorio\u2019 (<em>El sue\u00f1o de una noche de verano<\/em>) y la expresi\u00f3n <em>break the ice<\/em> \u2018romper el hielo\u2019 (<em>La fierecilla domada<\/em>). Muchas de ellas siguen formando parte de la lengua inglesa actual y han sido adoptadas por otras lenguas mediante pr\u00e9stamos, calcos u otras t\u00e9cnicas de traducci\u00f3n. Cuesta incluso creer que en un momento dado dichas palabras no existieran. Es indudable, por lo tanto, la gran repercusi\u00f3n que tuvo la obra de Shakespeare no solo en la literatura, sino tambi\u00e9n en la lengua.<\/p>\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/11\/hamletiano_500.jpg\"><img decoding=\"async\" class=\"wp-image-7916\" src=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/11\/hamletiano_500.jpg\" alt=\"[fotograf\u00eda] detalle de encrucijada de v\u00edas ferroviarias\"><\/a><figcaption>Hands off my tags! Michael Gaida (Pixabay)<\/figcaption><\/figure>\n\n\n<p>Hoy, sin embargo, podemos decir que su aportaci\u00f3n l\u00e9xica ha sobrepasado su obra, ya que su propio nombre ha originado el adjetivo <em>shakespeariano, shakespeariana<\/em>, que el <em>DLE<\/em> incluy\u00f3 en su 23.\u00aa edici\u00f3n con los significados de \u00abperteneciente o relativo a William Shakespeare, poeta y dramaturgo ingl\u00e9s\u00bb y \u00abpropio de William Shakespeare\u00bb. Si bien es algo habitual que los nombres de grandes figuras den pie a adjetivos relacionales (es ejemplo de ello el neologismo <em><a href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/orwelliano-orwelliana\/\" style=\"color: #2d9659;\">orwelliano, orwelliana<\/a><\/em>  y las voces recogidas ya en el <em>DLE<\/em> <em>brechtiano, brechtiana<\/em>; <em>copernicano, copernicana<\/em>; <em>euclidiano, euclidiana<\/em>; y <em>calderoniano, calderoniana<\/em>, entre otras), lo que Shakespeare nunca hubiera podido imaginar es que uno de sus personajes m\u00e1s ilustres, Hamlet, tambi\u00e9n originar\u00eda un nuevo vocablo.<\/p>\n\n\n\n<p>El sufijo &#8211;<em>iano<\/em>, uno de los m\u00e1s productivos en la creaci\u00f3n de adjetivos a partir de nombres propios, se a\u00f1ade al nombre del personaje principal de <em>La tragedia de Hamlet, pr\u00edncipe de Dinamarca<\/em> \u2014m\u00e1s conocida simplemente como <em>Hamlet<\/em>\u2014 para crear <em>hamletiano, hamletiana<\/em>. La adjetivaci\u00f3n de <em>Hamlet<\/em> ocasiona, por un lado, el adjetivo relacional que sirve para hacer referencia tanto a la obra escrita por Shakespeare como a su personaje principal:<\/p>\n\n\n\n<ul>\n<li>Yo prefiero el universo <strong>hamletiano<\/strong> de c\u00f3digos morales en la selva que retrataban en la maravillosa Muerte entre las flores, la cazurrer\u00eda, el desquiciamiento, la violencia y la villan\u00eda de la Am\u00e9rica profunda. [<em>El Pa\u00eds<\/em> (Espa\u00f1a), 26\/2\/2008]<\/li>\n\n\n\n<li>El resto, como dir\u00eda el personaje <strong>hamletiano<\/strong>, es silencio. [<em>Fotogramas<\/em> (Espa\u00f1a), 1\/6\/2020]<\/li>\n<\/ul>\n\n\n\n<p>Pero si por alguna cosa es recordada esta obra de Shakespeare es por la l\u00ednea que inicia el tercer acto. A Hamlet, ante la fatalidad de los hechos que ha descubierto e inmerso en un conflicto interior extenuante, le asaltan las dudas y profiere: \u00abSer, o no ser, esa es la cuesti\u00f3n\u00bb (\u00abTo be, or not to be, that is the question\u00bb, en el original). Esta escena, que ha trascendido el \u00e1mbito literario y se ha convertido en una de las m\u00e1s representadas y versionadas de toda la historia, ha dado lugar a que el adjetivo <em>hamletiano, hamletiana<\/em>, por otro lado, denomine el hecho de tener que escoger una opci\u00f3n entre dos opuestas:<\/p>\n\n\n\n<ul>\n<li>El primer secretario del PSC apunt\u00f3 que CDC afronta el \u00abdilema <strong>hamletiano<\/strong>\u00bb de optar por el di\u00e1logo con las otras fuerzas catalanas&#8230; [<em>La Vanguardia<\/em> (Espa\u00f1a), 18\/5\/1991]<\/li>\n\n\n\n<li>La defenestraci\u00f3n de Ibarra disipar\u00eda, con el correr del calendario, las dudas <strong>hamletianas<\/strong> del expresidente de Boca. [<em>Pagina12<\/em> (Argentina), 21\/8\/2008]<\/li>\n\n\n\n<li>Tres veces capados, resulta inveros\u00edmil que ahora, con motivo de una carta escrita en lat\u00edn, se pretenda poner a la sociedad en un dilema <strong>hamletiano<\/strong>: \u00bfnegociar o no negociar? [<em>El Espectador<\/em> (Colombia), 21\/1\/2012]<\/li>\n\n\n\n<li>\u00bfSer\u00e1 acaso un dilema <strong>hamletiano<\/strong>? [<em>El Comercio<\/em> (Per\u00fa), 27\/7\/2020]<\/li>\n<\/ul>\n\n\n\n<p>As\u00ed pues, ante una situaci\u00f3n disyuntiva son frecuentes las colocaciones <em>duda hamletiana<\/em> y <em>dilema hamletiano<\/em>. Partiendo de este significado, el adjetivo por s\u00ed solo se emplea tambi\u00e9n para describir algo que es ambiguo, contradictorio e incluso misterioso:<\/p>\n\n\n\n<ul>\n<li>Y seguimos at\u00f3nitos el deshojar de la margarita de nuestros <strong>hamletianos<\/strong> jueces (\u00a1c\u00f3mo se parece el frufr\u00fa de las togas al de las ropas talares!) sobre la huelga (ser\u00e1, no ser\u00e1, claudicar\u00e1 Bermejo, no lo har\u00e1&#8230;) del 18 de febrero. [<em>La Opini\u00f3n de M\u00e1laga<\/em> (Espa\u00f1a), 1\/2\/2009]<\/li>\n<\/ul>\n\n\n\n<p><em>Hamletiano, hamletiana<\/em> se recoge desde la creaci\u00f3n del BOBNEO, aunque para el espa\u00f1ol solo <em>Alvar2<\/em> lo documenta. Por lo que respecta a otras lenguas, el equivalente franc\u00e9s (<em>haml\u00e9tique<\/em>) se recoge en <em>Le Grand Robert<\/em> y el italiano (<em>amletico, amletica<\/em>) en <em>Lo Zingarelli<\/em>. Lo m\u00e1s curioso es que el <em>Oxford English Dictionary<\/em> no recoge <em>hamletian<\/em>, pero s\u00ed los derivados <em>hamletish<\/em> (adj.), <em>hamletism<\/em> (sust.) y <em>hamletize<\/em> (v.).<\/p>\n\n\n\n<p>En definitiva, esperemos que no sea necesario que trascurran casi quinientos a\u00f1os m\u00e1s, como ha ocurrido con <em>shakespeariano, shakespeariana<\/em>, para ver recogido <em>hamletiano, hamletiana<\/em> en el diccionario. Su uso ininterrumpido desde hace m\u00e1s de tres d\u00e9cadas en diferentes partes del territorio hispanohablante resuelve el dilema hamletiano de si este neologismo debe ser, o no ser, parte del diccionario.<\/p>\n\n\n\n<p>Laia Panad\u00e8s P\u00e9rez<br>Universitat Pompeu Fabra (Espa\u00f1a)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>William Shakespeare (Stratford-on-Avon, 1564-1616) es conocido por su faceta como poeta, dramaturgo y actor, y es considerado uno de los autores m\u00e1s c\u00e9lebres e influyentes de la literatura inglesa y universal. Sin embargo, no es tan conocido por su faceta de ne\u00f3logo. De las m\u00e1s de 1600 palabras que se le atribuyen, algunas fueron creadas por \u00e9l y otras simplemente las populariz\u00f3, pues, si bien se utilizaban, no se hab\u00edan plasmado nunca en papel. Acu\u00f1\u00f3 palabras como, por ejemplo, <em>gossip<\/em> \u2018chismorrear\u2019, que aparece en <em>La comedia de las equivocaciones<\/em>, <em>lonely<\/em> \u2018solo, -la\u2019 (<em>Coriolano<\/em>), y <em>bedroom<\/em> \u2018dormitorio\u2019 (<em>El sue\u00f1o de una noche de verano<\/em>) y la expresi\u00f3n <em>break the ice<\/em> \u2018romper el hielo\u2019 (<em>La fierecilla domada<\/em>). Muchas de ellas siguen formando parte de la lengua inglesa actual y han sido adoptadas por otras lenguas mediante pr\u00e9stamos, calcos u otras t\u00e9cnicas de traducci\u00f3n. Cuesta incluso creer que en un momento dado dichas palabras no existieran. Es indudable, por lo tanto, la gran repercusi\u00f3n que tuvo la obra de Shakespeare no solo en la literatura, sino tambi\u00e9n en la lengua.<\/p>\n","protected":false},"author":1,"featured_media":10769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_s2mail":""},"categories":[98,37],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CVC. Hamletiano, hamletiana | Martes Neol\u00f3gico<\/title>\n<meta name=\"description\" content=\"Art\u00edculo sobre el neologismo \u00abhamletiano, hamletiana\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CVC. Hamletiano, hamletiana | Martes Neol\u00f3gico\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo sobre el neologismo \u00abhamletiano, hamletiana\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Martes Neol\u00f3gico\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-15T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T13:24:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/11\/hamletiano_350.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\"},\"headline\":\"hamletiano, hamletiana adj.\",\"datePublished\":\"2022-11-15T05:00:00+00:00\",\"dateModified\":\"2025-07-30T13:24:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/\"},\"wordCount\":886,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"articleSection\":[\"literatura\",\"sufijaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/\",\"name\":\"CVC. Hamletiano, hamletiana | Martes Neol\u00f3gico\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\"},\"datePublished\":\"2022-11-15T05:00:00+00:00\",\"dateModified\":\"2025-07-30T13:24:15+00:00\",\"description\":\"Art\u00edculo sobre el neologismo \u00abhamletiano, hamletiana\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\",\"breadcrumb\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"hamletiano, hamletiana adj.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"name\":\"Martes Neol\u00f3gico\",\"description\":\"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario\",\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\",\"name\":\"Martes Neol\u00f3gico\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"contentUrl\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"width\":300,\"height\":100,\"caption\":\"Martes Neol\u00f3gico\"},\"image\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CVC. Hamletiano, hamletiana | Martes Neol\u00f3gico","description":"Art\u00edculo sobre el neologismo \u00abhamletiano, hamletiana\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/","og_locale":"es_ES","og_type":"article","og_title":"CVC. Hamletiano, hamletiana | Martes Neol\u00f3gico","og_description":"Art\u00edculo sobre el neologismo \u00abhamletiano, hamletiana\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","og_url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/","og_site_name":"Martes Neol\u00f3gico","article_published_time":"2022-11-15T05:00:00+00:00","article_modified_time":"2025-07-30T13:24:15+00:00","og_image":[{"width":750,"height":350,"url":"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/11\/hamletiano_350.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#article","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/"},"author":{"name":"admin","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47"},"headline":"hamletiano, hamletiana adj.","datePublished":"2022-11-15T05:00:00+00:00","dateModified":"2025-07-30T13:24:15+00:00","mainEntityOfPage":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/"},"wordCount":886,"commentCount":0,"publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"articleSection":["literatura","sufijaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/","name":"CVC. Hamletiano, hamletiana | Martes Neol\u00f3gico","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website"},"datePublished":"2022-11-15T05:00:00+00:00","dateModified":"2025-07-30T13:24:15+00:00","description":"Art\u00edculo sobre el neologismo \u00abhamletiano, hamletiana\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","breadcrumb":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hamletiano-hamletiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/"},{"@type":"ListItem","position":2,"name":"hamletiano, hamletiana adj."}]},{"@type":"WebSite","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","name":"Martes Neol\u00f3gico","description":"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario","publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization","name":"Martes Neol\u00f3gico","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","contentUrl":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","width":300,"height":100,"caption":"Martes Neol\u00f3gico"},"image":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10754"}],"collection":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/comments?post=10754"}],"version-history":[{"count":6,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10754\/revisions"}],"predecessor-version":[{"id":13498,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10754\/revisions\/13498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media\/10769"}],"wp:attachment":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media?parent=10754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/categories?post=10754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/tags?post=10754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}