{"id":10928,"date":"2022-12-20T07:00:00","date_gmt":"2022-12-20T05:00:00","guid":{"rendered":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?p=10928"},"modified":"2025-07-30T15:20:24","modified_gmt":"2025-07-30T13:20:24","slug":"goticula","status":"publish","type":"post","link":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/","title":{"rendered":"got\u00edcula <em>f.<\/em>"},"content":{"rendered":"\n<p>La palabra <em>got\u00edcula<\/em> se utiliza para designar aquellas peque\u00f1as gotas de saliva a trav\u00e9s de las cuales se propaga un virus. Esta capacidad transmisiva es lo que diferencia sem\u00e1nticamente <em>got\u00edcula<\/em> de <em>gotita<\/em> y la que explica, adem\u00e1s, su fuerte presencia en los medios durante la pandemia. <em>Got\u00edcula<\/em> es un t\u00e9rmino especializado perteneciente al \u00e1mbito de las ciencias que ha pasado al uso com\u00fan, lo que permite considerarlo como un neologismo. El mecanismo de formaci\u00f3n que est\u00e1 presente es la adici\u00f3n del diminutivo latino <em>-culo<\/em>, <em>-cula<\/em> \u2018peque\u00f1o\u2019 a la palabra <em>gota<\/em>, el mismo mecanismo que podemos encontrar en otras entradas del diccionario, como <em>mont\u00edculo<\/em>, <em>espir\u00e1culo<\/em>, <em>mol\u00e9cula<\/em> o <em>vulp\u00e9cula<\/em>.<\/p>\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"\"><\/a><\/figure>\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/12\/goticula_500.jpg\"><img decoding=\"async\" class=\"wp-image-7916\" src=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/12\/goticula_500.jpg\" alt=\"[fotograf\u00eda] peque\u00f1as gotas de agua aumentadas por visi\u00f3n microsc\u00f3pica, sobre una superficie vegetal de color verde\"><\/a><figcaption>Egor Kamelev (Pexels)<\/figcaption><\/figure>\n\n\n<p>El primer registro hallado pertenece, curiosamente, al \u00e1mbito de la literatura, y se encuentra en el poema \u00abNihil novum\u00bb de Amado Nervo, texto que data de 1900:<\/p>\n\n\n\n<ul>\n<li>Mi libro s\u00f3lo es, en suma \/ <strong>got\u00edcula<\/strong> entre la bruma [&#8230;]<\/li>\n<\/ul>\n\n\n\n<p>No obstante, salvo este uso literario, desde la primera mitad del siglo <span class=\"versalitas\">xx<\/span> hasta la llegada de la pandemia, la palabra estaba circunscrita al \u00e1mbito de las ciencias. Con la llegada de la COVID-19, el neologismo <em>got\u00edcula<\/em> adquiri\u00f3 una particular relevancia en la prensa de diferentes pa\u00edses del \u00e1mbito hisp\u00e1nico, alternando con variantes como <em>gotas virales<\/em> o <em>microgotas<\/em>. Es posible encontrarla, con bastante frecuencia, en peri\u00f3dicos tanto de Espa\u00f1a como de Am\u00e9rica, sobre todo durante el a\u00f1o 2020, tal como podemos observar en los siguientes ejemplos:<\/p>\n\n\n\n<p>La b\u00fasqueda en prensa no solo evidencia que tiene un uso generalizado en todo el mundo hispanohablante, sino que tambi\u00e9n da cuenta de que su frecuencia de uso fue muy alta en 2020, pero que ha ido disminuyendo abruptamente. Sin embargo, durante el presente a\u00f1o, la llegada de la viruela del mono parece haber influido en un resurgimiento de las apariciones en prensa del neologismo en cuesti\u00f3n.<\/p>\n\n\n\n<p>En relaci\u00f3n con su registro en las obras lexicogr\u00e1ficas de referencia, destaca el hecho de que ninguna de ellas ha recogido la palabra, lo que se explica debido a su car\u00e1cter especializado. Lo mismo sucede con los corpus de la Academia: no se encuentran resultados en ninguno de ellos, lo que refuerza la idea de que es un t\u00e9rmino circunscrito al \u00e1mbito de las ciencias. Ahora bien, si ampliamos la b\u00fasqueda, es posible encontrar un registro en el <em>Diccionario polit\u00e9cnico de las lenguas espa\u00f1ola e inglesa<\/em> (Beigbeder, 1997), en donde se presenta como la traducci\u00f3n de la palabra inglesa <em>droplet<\/em>, y otro en el <em>Diccionario de t\u00e9rminos m\u00e9dicos<\/em> (<em>DTM<\/em>) de la Real Academia Nacional de Medicina de Espa\u00f1a, en cuya obra remite a <em>gotita<\/em>, aunque con la observaci\u00f3n de que \u00ab[&#8230;] la preferencia por una variante u otra depende del contexto\u00bb.<\/p>\n\n\n\n<p>En otras lenguas, la situaci\u00f3n es similar, pues no se registra en las obras de referencia del catal\u00e1n, italiano ni franc\u00e9s (<em>DIEC2<\/em>, <em>Dizionario Hoepli della lingua italiana<\/em> y <em>Le Grand Robert<\/em>, respectivamente). En portugu\u00e9s, <em>goticula<\/em> es recogida por el <em>Dicion\u00e1rio Priberam Online de Portugu\u00eas Contempor\u00e2neo<\/em> en sus dos acepciones: como una palabra de uso com\u00fan (\u00abpeque\u00f1a gota\u00bb) y como un t\u00e9rmino especializado del \u00e1mbito de la medicina, con el mismo sentido que en espa\u00f1ol.<\/p>\n\n\n\n<p>As\u00ed, pues, considerando su alta presencia en prensa y su ausencia en las principales obras lexicogr\u00e1ficas del espa\u00f1ol, cabe preguntarse si <em>got\u00edcula<\/em> lograr\u00e1 permear de forma definitiva en el l\u00e9xico general, o bien permanecer\u00e1 circunscrita al \u00e1mbito especializado. Para intentar responder a ello, consideremos lo siguiente: en primer lugar, llama la atenci\u00f3n que gran parte de sus apariciones en prensa corresponden a citas directas de especialistas, o van acompa\u00f1adas de una definici\u00f3n o reformulaci\u00f3n del t\u00e9rmino; luego, destaca el hecho de que su frecuencia de uso ha ido decayendo en la medida en que la preocupaci\u00f3n por la pandemia parece ir en la misma direcci\u00f3n, aunque debemos considerar que sus registros en prensa han aumentado desde la aparici\u00f3n de la viruela del mono; finalmente, la presencia de la palabra en espacios diferentes a los ya mencionados, como foros o comentarios en redes sociales, es pr\u00e1cticamente inexistente, por lo que parece mantener a\u00fan cierto car\u00e1cter disciplinar.<\/p>\n\n\n\n<p>Lo anterior nos lleva a pensar en que, pese a su marcado car\u00e1cter especializado, la palabra <em>got\u00edcula<\/em> merece su inclusi\u00f3n en las obras lexicogr\u00e1ficas espa\u00f1olas, pues su alta frecuencia de uso en prensa durante los \u00faltimos tres a\u00f1os permite respaldarlo. Asimismo, tenemos que considerar que, ante la eventual aparici\u00f3n de nuevas variantes de la COVID-19 o, como ya ha ocurrido con la viruela s\u00edmica, lo m\u00e1s probable es que los hablantes tendamos a echar mano de aquellos neologismos que han surgido \u2014o resurgido\u2014 durante la pandemia.<\/p>\n\n\n\n<p>Gabriel Vald\u00e9s Le\u00f3n<br>Grupo de Investigaci\u00f3n reconocido \u00abMotivaci\u00f3n, Educaci\u00f3n y Salud\u00bb<br>Universidad de Las Palmas de Gran Canaria (Espa\u00f1a)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La palabra <em>got\u00edcula<\/em> se utiliza para designar aquellas peque\u00f1as gotas de saliva a trav\u00e9s de las cuales se propaga un virus. Esta capacidad transmisiva es lo que diferencia sem\u00e1nticamente <em>got\u00edcula<\/em> de <em>gotita<\/em> y la que explica, adem\u00e1s, su fuerte presencia en los medios durante la pandemia. <em>Got\u00edcula<\/em> es un t\u00e9rmino especializado perteneciente al \u00e1mbito de las ciencias que ha pasado al uso com\u00fan, lo que permite considerarlo como un neologismo. El mecanismo de formaci\u00f3n que est\u00e1 presente es la adici\u00f3n del diminutivo latino <em>-culo<\/em>, <em>-cula<\/em> \u2018peque\u00f1o\u2019 a la palabra <em>gota<\/em>, el mismo mecanismo que podemos encontrar en otras entradas del diccionario, como <em>mont\u00edculo<\/em>, <em>espir\u00e1culo<\/em>, <em>mol\u00e9cula<\/em> o <em>vulp\u00e9cula<\/em>.<\/p>\n","protected":false},"author":1,"featured_media":10934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_s2mail":""},"categories":[73,37],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CVC. Got\u00edcula | Martes Neol\u00f3gico<\/title>\n<meta name=\"description\" content=\"Art\u00edculo sobre el neologismo \u00abgot\u00edcula\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CVC. Got\u00edcula | Martes Neol\u00f3gico\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo sobre el neologismo \u00abgot\u00edcula\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/\" \/>\n<meta property=\"og:site_name\" content=\"Martes Neol\u00f3gico\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-20T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T13:20:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/12\/goticula_350.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\"},\"headline\":\"got\u00edcula f.\",\"datePublished\":\"2022-12-20T05:00:00+00:00\",\"dateModified\":\"2025-07-30T13:20:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/\"},\"wordCount\":854,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"articleSection\":[\"salud\",\"sufijaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/\",\"name\":\"CVC. Got\u00edcula | Martes Neol\u00f3gico\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\"},\"datePublished\":\"2022-12-20T05:00:00+00:00\",\"dateModified\":\"2025-07-30T13:20:24+00:00\",\"description\":\"Art\u00edculo sobre el neologismo \u00abgot\u00edcula\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\",\"breadcrumb\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"got\u00edcula f.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"name\":\"Martes Neol\u00f3gico\",\"description\":\"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario\",\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\",\"name\":\"Martes Neol\u00f3gico\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"contentUrl\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"width\":300,\"height\":100,\"caption\":\"Martes Neol\u00f3gico\"},\"image\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CVC. Got\u00edcula | Martes Neol\u00f3gico","description":"Art\u00edculo sobre el neologismo \u00abgot\u00edcula\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/","og_locale":"es_ES","og_type":"article","og_title":"CVC. Got\u00edcula | Martes Neol\u00f3gico","og_description":"Art\u00edculo sobre el neologismo \u00abgot\u00edcula\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","og_url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/","og_site_name":"Martes Neol\u00f3gico","article_published_time":"2022-12-20T05:00:00+00:00","article_modified_time":"2025-07-30T13:20:24+00:00","og_image":[{"width":750,"height":350,"url":"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2022\/12\/goticula_350.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#article","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/"},"author":{"name":"admin","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47"},"headline":"got\u00edcula f.","datePublished":"2022-12-20T05:00:00+00:00","dateModified":"2025-07-30T13:20:24+00:00","mainEntityOfPage":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/"},"wordCount":854,"commentCount":1,"publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"articleSection":["salud","sufijaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/","name":"CVC. Got\u00edcula | Martes Neol\u00f3gico","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website"},"datePublished":"2022-12-20T05:00:00+00:00","dateModified":"2025-07-30T13:20:24+00:00","description":"Art\u00edculo sobre el neologismo \u00abgot\u00edcula\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","breadcrumb":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/goticula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/"},{"@type":"ListItem","position":2,"name":"got\u00edcula f."}]},{"@type":"WebSite","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","name":"Martes Neol\u00f3gico","description":"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario","publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization","name":"Martes Neol\u00f3gico","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","contentUrl":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","width":300,"height":100,"caption":"Martes Neol\u00f3gico"},"image":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10928"}],"collection":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/comments?post=10928"}],"version-history":[{"count":2,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10928\/revisions"}],"predecessor-version":[{"id":13489,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10928\/revisions\/13489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media\/10934"}],"wp:attachment":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media?parent=10928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/categories?post=10928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/tags?post=10928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}