{"id":10997,"date":"2023-01-17T07:00:00","date_gmt":"2023-01-17T05:00:00","guid":{"rendered":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?p=10997"},"modified":"2023-01-26T09:41:22","modified_gmt":"2023-01-26T07:41:22","slug":"posmemoria","status":"publish","type":"post","link":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/","title":{"rendered":"posmemoria <em>f.<\/em>"},"content":{"rendered":"\n<p>Debemos al pol\u00edtico franc\u00e9s Camille S\u00e9e (1847-1919) la frase \u00abDicen que la historia se repite, pero lo cierto es que sus lecciones no se aprovechan\u00bb. Un siglo despu\u00e9s, todo parece indicar que seguimos sin aprender y seguimos tropezando con piedras que aparecen de manera c\u00edclica y que seguimos sin saber esquivar: solo durante el siglo <span class=\"versalitas\">xx<\/span> hemos asistido a exterminaciones deliberadas y sistem\u00e1ticas, como el genocidio armenio (1915-1923), al Holocausto jud\u00edo (1933-1945), el genocidio camboyano (1975-1979), el genocidio de Ruanda (1994) o la masacre de Srebrenica (1995). Aunque el horror se repita, persiste.<\/p>\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"\"><\/a><\/figure>\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2023\/01\/posmemoria_500.jpg\"><img decoding=\"async\" class=\"wp-image-7916\" src=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2023\/01\/posmemoria_500.jpg\" alt=\"[fotograf\u00eda] cirio encendido junto a una ventana\"><\/a><figcaption>Rene Asmussen (Pexels)<\/figcaption><\/figure>\n\n\n<p>En el art\u00edculo dedicado al sintagma <a style=\"color: #2d9659;\" href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/memoria-historica\/\"><em>memoria hist\u00f3rica<\/em><\/a>, ya se observ\u00f3 que tomaba un significado con intenci\u00f3n reivindicativa: la de no omitir o minimizar unos hechos injustos que se han silenciado por alg\u00fan motivo. Tambi\u00e9n sobre la base <em>memoria<\/em> se construye el neologismo lexicogr\u00e1fico formado por prefijaci\u00f3n <em>posmemoria<\/em>, que, si bien <em>a priori<\/em> puede parecer una construcci\u00f3n extra\u00f1a, puesto que el prefijo <em>pos(t)-<\/em> tiende a adjuntarse con adjetivos (<em>posnatal<\/em>, <em>postraum\u00e1tico -ca<\/em>, <em>posmoderno<\/em>), tambi\u00e9n se puede encontrar formando sustantivos (<em>posguerra<\/em>, <em>posventa<\/em> o la m\u00e1s reciente <em>posverdad<\/em>).<\/p>\n\n\n\n<p>El t\u00e9rmino <em>posmemoria<\/em> fue acu\u00f1ado en 1992 por Marianne Hirsch, catedr\u00e1tica de ingl\u00e9s y literatura comparada en la Universidad de Columbia (Estados Unidos), para aludir al proceso de elaboraci\u00f3n de la memoria traum\u00e1tica del Holocausto por parte de las generaciones posteriores, principalmente la de los hijos de los supervivientes del genocidio jud\u00edo, que se basa en los recuerdos de sus padres (fotograf\u00edas, documentos, relatos, objetos). En definitiva, hace referencia a c\u00f3mo la \u00abgeneraci\u00f3n de despu\u00e9s\u00bb convive con el trauma personal y colectivo de sus predecesores, que transfieren su experiencia de un modo tan v\u00edvido y emotivo a los hijos que estos lo acaban sintiendo como si se tratara de recuerdos propios.<\/p>\n\n\n\n<p>Este concepto, aunque no ha quedado exento de cr\u00edticas, goza de una gran aceptaci\u00f3n entre los expertos y ha demostrado ser de una gran eficacia para analizar y contabilizar casos de la relaci\u00f3n que las generaciones posteriores o los testigos contempor\u00e1neos distantes mantienen con el trauma personal, colectivo y cultural de los dem\u00e1s, y hasta experiencias que ellos \u00abrecuerdan\u00bb o conocen solo por medio de historias, im\u00e1genes y comportamientos. Se comenz\u00f3 a aplicar a guerras y dictaduras de la historia reciente como las de Am\u00e9rica del Sur en la segunda mitad del siglo pasado o la guerra civil espa\u00f1ola:<\/p>\n\n\n\n<ul><li>La <strong>posmemoria<\/strong> se distingue de la memoria por una diferencia generacional y de la historia por una diferencia generacional y de la historia por una conexi\u00f3n personal. [<em>Historia Cr\u00edtica<\/em> (Colombia), 1\/1\/2010]<\/li><\/ul>\n\n\n\n<ul><li>\u00bfCu\u00e1l es la relaci\u00f3n de la <strong>posmemoria<\/strong> con el arte y la arquitectura (sobre todo, con los contramonumentos)? [<em>Clar\u00edn<\/em> (Argentina), 18\/10\/2016]<\/li><\/ul>\n\n\n\n<ul><li>Frente a la operaci\u00f3n de incorporaci\u00f3n que tiene la memoria hist\u00f3rica, la cual cancela la cr\u00edtica, ofrece una lectura de algo llamado <strong>posmemoria<\/strong> y su dimensi\u00f3n est\u00e9tico-pol\u00edtica: recupera el conflicto social sin reducirlo a su variante traum\u00e1tica, en una especie de conexi\u00f3n generacional. [<em>La Jornada<\/em> (M\u00e9xico), 13\/10\/2019]<\/li><\/ul>\n\n\n\n<ul><li>El volumen intenta arrojar luz sobre las miles de historias del exilio desde novedosas y diversas perspectivas historiogr\u00e1ficas como los \u00abpuntos de memoria\u00bb, una intersecci\u00f3n entre la memoria personal y el recuerdo cultural, el estudio del trabajo de la <strong>posmemoria<\/strong> en las familias de refugiados o el de la manera de transmisi\u00f3n de los valores pol\u00edticos de una generaci\u00f3n a otra. [<em>La Vanguardia<\/em>, 25\/2\/2022]<\/li><\/ul>\n\n\n\n<ul><li>Vivimos en tiempos de <strong>posmemoria<\/strong>, desprestigio del hecho real, fe en lo virtual y ausente, defenestraciones autobiogr\u00e1ficas. Como si las autobiograf\u00edas no fuesen representaciones de la precariedad y del miedo. [<em>El Pa\u00eds<\/em> (Espa\u00f1a), 14\/11\/2022]<\/li><\/ul>\n\n\n\n<p>Mediante la <em>posmemoria<\/em>, pues, se pueden recuperar vivencias de la transmisi\u00f3n intergeneracional con el objetivo de superar el dolor a partir del recuerdo com\u00fan para que devenga compartido: algunos aspectos clave que se tienen en cuenta son la necesidad de maduraci\u00f3n del trauma heredado, la mediaci\u00f3n y manipulaci\u00f3n art\u00edstica o la instrumentalizaci\u00f3n de las fotograf\u00edas como medio de proyecci\u00f3n emocional y de reconocimiento del pasado.<\/p>\n\n\n\n<p>La palabra no se ha documentado todav\u00eda en ning\u00fan repertorio lexicogr\u00e1fico, ni del espa\u00f1ol ni de otras lenguas. Seg\u00fan la expresi\u00f3n de Primo Levi, por \u00abdeber de memoria\u00bb esta situaci\u00f3n deber\u00eda ser resarcida.<\/p>\n\n\n\n<p>Elisenda Bernal<br>Observatori de Neologia<br>Universitat Pompeu Fabra (Espa\u00f1a)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debemos al pol\u00edtico franc\u00e9s Camille S\u00e9e (1847-1919) la frase \u00abDicen que la historia se repite, pero lo cierto es que sus lecciones no se aprovechan\u00bb. Un siglo despu\u00e9s, todo parece indicar que seguimos sin aprender y seguimos tropezando con piedras que aparecen de manera c\u00edclica y que seguimos sin saber esquivar: solo durante el siglo <span class=\"versalitas\">xx<\/span> hemos asistido a exterminaciones deliberadas y sistem\u00e1ticas, como el genocidio armenio (1915-1923), al Holocausto jud\u00edo (1933-1945), el genocidio camboyano (1975-1979), el genocidio de Ruanda (1994) o la masacre de Srebrenica (1995). Aunque el horror se repita, persiste.<\/p>\n","protected":false},"author":1,"featured_media":11000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_s2mail":""},"categories":[75,52],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CVC. Posmemoria | Martes Neol\u00f3gico<\/title>\n<meta name=\"description\" content=\"Art\u00edculo sobre el neologismo \u00abposmemoria\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CVC. Posmemoria | Martes Neol\u00f3gico\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo sobre el neologismo \u00abposmemoria\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Martes Neol\u00f3gico\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-17T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T07:41:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2023\/01\/posmemoria_350.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\"},\"headline\":\"posmemoria f.\",\"datePublished\":\"2023-01-17T05:00:00+00:00\",\"dateModified\":\"2023-01-26T07:41:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/\"},\"wordCount\":770,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"articleSection\":[\"historia\",\"prefijaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/\",\"name\":\"CVC. Posmemoria | Martes Neol\u00f3gico\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\"},\"datePublished\":\"2023-01-17T05:00:00+00:00\",\"dateModified\":\"2023-01-26T07:41:22+00:00\",\"description\":\"Art\u00edculo sobre el neologismo \u00abposmemoria\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\",\"breadcrumb\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"posmemoria f.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"name\":\"Martes Neol\u00f3gico\",\"description\":\"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario\",\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\",\"name\":\"Martes Neol\u00f3gico\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"contentUrl\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"width\":300,\"height\":100,\"caption\":\"Martes Neol\u00f3gico\"},\"image\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CVC. Posmemoria | Martes Neol\u00f3gico","description":"Art\u00edculo sobre el neologismo \u00abposmemoria\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/","og_locale":"es_ES","og_type":"article","og_title":"CVC. Posmemoria | Martes Neol\u00f3gico","og_description":"Art\u00edculo sobre el neologismo \u00abposmemoria\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","og_url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/","og_site_name":"Martes Neol\u00f3gico","article_published_time":"2023-01-17T05:00:00+00:00","article_modified_time":"2023-01-26T07:41:22+00:00","og_image":[{"width":750,"height":350,"url":"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2023\/01\/posmemoria_350.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#article","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/"},"author":{"name":"admin","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47"},"headline":"posmemoria f.","datePublished":"2023-01-17T05:00:00+00:00","dateModified":"2023-01-26T07:41:22+00:00","mainEntityOfPage":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/"},"wordCount":770,"commentCount":0,"publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"articleSection":["historia","prefijaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/","name":"CVC. Posmemoria | Martes Neol\u00f3gico","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website"},"datePublished":"2023-01-17T05:00:00+00:00","dateModified":"2023-01-26T07:41:22+00:00","description":"Art\u00edculo sobre el neologismo \u00abposmemoria\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","breadcrumb":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/posmemoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/"},{"@type":"ListItem","position":2,"name":"posmemoria f."}]},{"@type":"WebSite","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","name":"Martes Neol\u00f3gico","description":"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario","publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization","name":"Martes Neol\u00f3gico","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","contentUrl":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","width":300,"height":100,"caption":"Martes Neol\u00f3gico"},"image":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10997"}],"collection":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/comments?post=10997"}],"version-history":[{"count":2,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10997\/revisions"}],"predecessor-version":[{"id":11048,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/10997\/revisions\/11048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media\/11000"}],"wp:attachment":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media?parent=10997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/categories?post=10997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/tags?post=10997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}