{"id":6920,"date":"2021-01-12T07:00:41","date_gmt":"2021-01-12T05:00:41","guid":{"rendered":"http:\/\/blogscvc.cervantes.es\/martes-neologico\/?p=6920"},"modified":"2025-08-01T10:03:35","modified_gmt":"2025-08-01T08:03:35","slug":"trap","status":"publish","type":"post","link":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/","title":{"rendered":"trap <em>m.<\/em> y <em>adj.<\/em>"},"content":{"rendered":"<p>El trap o la m\u00fasica trap es un subg\u00e9nero del <span style=\"color: #2d9659;\"><a style=\"color: #2d9659;\" href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hip-hop\/\" target=\"_blank\" rel=\"noopener\"> hip hop<\/a><\/span> que apareci\u00f3 a finales de los a\u00f1os noventa en el sur de los Estados Unidos. Se empez\u00f3 a popularizar a partir del 2010, pero no lleg\u00f3 a su plenitud hasta el 2015, y desde entonces el inter\u00e9s por el trap ha ido creciendo hasta convertirse en el g\u00e9nero musical <em>mainstream<\/em> que es actualmente. El hecho de que alcanzara la popularidad recientemente explica por qu\u00e9 es un neologismo que no aparece en ninguno de los diccionarios de referencia del espa\u00f1ol: ni en los de uso, como <em>Clave <\/em>o <em>VOXUSO<\/em>, ni en los que son espec\u00edficamente neol\u00f3gicos, como <em>Alvar1<\/em>, <em>Alvar2<\/em> o <em>NEOMM<\/em>. Es m\u00e1s, tampoco aparece en los diccionarios de referencia del ingl\u00e9s, del franc\u00e9s o del italiano. En el caso del ingl\u00e9s esta ausencia es especialmente sorprendente, puesto que el <em>Oxford English Dictionary<\/em> se actualiza cuatro veces al a\u00f1o y suele tardar poco tiempo en a\u00f1adir entradas de neologismos que han aparecido recientemente.<\/p>\n<figure id=\"attachment_118\" aria-describedby=\"caption-attachment-118\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2021\/01\/trap_500.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-1739\" src=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2021\/01\/trap_500.jpg\" alt=\"Fotograf\u00eda del artista Bad Bunny.\" width=\"750\" height=\"500\"><\/a><figcaption id=\"caption-attachment-118\" class=\"wp-caption-text\">Google Images<\/figcaption><\/figure>\n<p>Los ejemplos encontrados en las fuentes period\u00edsticas de todo el dominio del espa\u00f1ol tambi\u00e9n reflejan la popularizaci\u00f3n reciente de este pr\u00e9stamo:<\/p>\n<ul>\n<li>Luego Dandrades pregunt\u00f3 al acompa\u00f1ante de Maluma: \u00bfY t\u00fa grabar\u00edas un <strong>trap<\/strong>? [<em>Per\u00fa 21<\/em> (Per\u00fa), 01\/06\/2017]<\/li>\n<li>Tras arrasar en el 2018 con \u00abSin Pijama\u00bb y \u00abCuando te bes\u00e9\u00bb, Becky G presenta su nueva producci\u00f3n de pop en ingl\u00e9s, <em>LBD<\/em>, un bombazo de <strong>trap<\/strong> que viene acompa\u00f1ado de un espectacular lyric video.&nbsp;[<em>El Universal <\/em>(Venezuela), 18\/01\/2019]<\/li>\n<li>La m\u00fasica que ya no es cumbia, sino <strong>trap<\/strong> y alg\u00fan tipo de reggaet\u00f3n. [<em>Clar\u00edn<\/em> (Argentina), 17\/08\/2019]<\/li>\n<li>El festival S\u00f3nar ofrecer\u00e1 en su nueva edici\u00f3n una amplia oferta musical y sonora protagonizada, seg\u00fan la organizaci\u00f3n, por h\u00e9roes del clubbing contempor\u00e1neo, la electr\u00f3nica de vanguardia y las figuras emergentes del <strong>trap<\/strong>. [<em>La Vanguardia<\/em> (Espa\u00f1a), 17\/01\/2020]<\/li>\n<li>Igual que la canci\u00f3n de Lil Nas X&nbsp;<em>Old Town Road,<\/em>que mezcla country con hip hop y <strong>trap<\/strong>, Breland fusiona juguetonamente trap en temas country en los que habla de caballos, mariguana y cerveza en su EP hom\u00f3nimo y canta sobre artistas country como Chase Rice y Lauren Alaina. [<em>La Jornada <\/em>(M\u00e9xico), 27\/06\/2020]<\/li>\n<\/ul>\n<p>Aunque en algunos casos el conocimiento de la lengua original facilita la comprensi\u00f3n de los pr\u00e9stamos, en el caso de <em>trap<\/em> el significado no es transparente. En ingl\u00e9s, los diccionarios recogen el sustantivo <em>trap<\/em> con el significado de \u2018trampa\u2019, pero en <em>trap (music)<\/em> el significado es neol\u00f3gico y originariamente dialectal y arg\u00f3tica, ya que se trata de una palabra propia de Atlanta (Georgia) que se usa para denominar un lugar en el que se venden drogas de forma ilegal, las <em>trap houses<\/em>. En las letras de sus canciones, los primeros artistas de trap hablaban a menudo de la adicci\u00f3n a las drogas, la violencia en las calles y el mundo de las <em>trap houses<\/em>, as\u00ed que el subg\u00e9nero recibi\u00f3 ese nombre.<\/p>\n<p>El estilo musical de esta mezcla entre el hip hop y la m\u00fasica electr\u00f3nica es muy minimalista, ya que en el <em>trap<\/em> se usan muy pocos instrumentos y el foco est\u00e1 m\u00e1s bien en los efectos sonoros: se vale principalmente de sintetizadores, cajas de ritmos, patrones variados de <em>hi-hat<\/em> (el sonido de dos platillos que forman parte de la bater\u00eda), acordes menores y una melod\u00eda modificada con <em>autotune<\/em> con letras que suelen contar historias sobre situaciones de precariedad en los barrios pobres. Dado el contexto en el que nace el trap, la est\u00e9tica de sus artistas suele reflejar ese ambiente, aunque la ropa t\u00edpicamente urbana que visten (como el ch\u00e1ndal) muy a menudo es un dise\u00f1o de marca, dada la popularidad que ha alcanzado la m\u00fasica trap actualmente.<\/p>\n<p>En el contexto internacional, se reconoce al productor Shawty Redd como uno de los pioneros del g\u00e9nero, y a Waka Floka como uno de los primeros artistas en crear este tipo de m\u00fasica en el 2010. Desde entonces, el trap es uno de los subg\u00e9neros m\u00e1s populares en Estados Unidos, con artistas como Drake, Cardi B o Travis Scott. En la m\u00fasica en espa\u00f1ol, el trap se ha relacionado a menudo con el reguet\u00f3n; aunque son g\u00e9neros distintos, se reconoce la existencia de un subg\u00e9nero espec\u00edfico llamado trap latino, que mezcla ambos estilos. Finalmente, en el contexto de Espa\u00f1a, una de las artistas que m\u00e1s ha experimentado con el trap es Rosal\u00eda, que lo mezcl\u00f3 con el flamenco en su \u00e1lbum <em>El mal querer<\/em>.<\/p>\n<p>Dada la incontestable popularidad del trap en todo el mundo (y especialmente en los pa\u00edses hispanohablantes con su rama de trap latino), la f\u00e1cil adaptaci\u00f3n del pr\u00e9stamo al sistema del espa\u00f1ol y el hecho de que los diccionarios de referencia ya incluyen otros g\u00e9neros musicales como el <em>rap<\/em>, ser\u00eda interesante considerar la posible inclusi\u00f3n del neologismo <em>trap<\/em> en el <em>DLE<\/em>, junto con el g\u00e9nero al que pertenece, el hip hop, que tampoco est\u00e1 recogido en el diccionario normativo de la lengua espa\u00f1ola.<\/p>\n<p>Alba Mil\u00e0 Garcia<br \/>\nUniversitat Aut\u00f2noma de Barcelona (Espa\u00f1a)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El trap o la m\u00fasica trap es un subg\u00e9nero del <span style=\"color: #2d9659;\"><a style=\"color: #2d9659;\" href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/hip-hop\/\" target=\"_blank\" rel=\"noopener\"> hip hop<\/a><\/span> que apareci\u00f3 a finales de los a\u00f1os noventa en el sur de los Estados Unidos. Se empez\u00f3 a popularizar a partir del 2010, pero no lleg\u00f3 a su plenitud hasta el 2015, y desde entonces el inter\u00e9s por el trap ha ido creciendo hasta convertirse en el g\u00e9nero musical <em>mainstream<\/em> que es actualmente. El hecho de que alcanzara la popularidad recientemente explica por qu\u00e9 es un neologismo que no aparece en ninguno de los diccionarios de referencia del espa\u00f1ol: ni en los de uso, como <em>Clave <\/em>o <em>VOXUSO<\/em>, ni en los que son espec\u00edficamente neol\u00f3gicos, como <em>Alvar1<\/em>, <em>Alvar2<\/em> o <em>NEOMM<\/em>. Es m\u00e1s, tampoco aparece en los diccionarios de referencia del ingl\u00e9s, del franc\u00e9s o del italiano. En el caso del ingl\u00e9s esta ausencia es especialmente sorprendente, puesto que el <em>Oxford English Dictionary<\/em> se actualiza cuatro veces al a\u00f1o y suele tardar poco tiempo en a\u00f1adir entradas de neologismos que han aparecido recientemente.<\/p>\n","protected":false},"author":1,"featured_media":6944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_s2mail":"yes"},"categories":[256,111,274],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CVC. Trap | Martes Neol\u00f3gico<\/title>\n<meta name=\"description\" content=\"Art\u00edculo sobre el neologismo \u00abtrap\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CVC. Trap | Martes Neol\u00f3gico\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo sobre el neologismo \u00abtrap\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/\" \/>\n<meta property=\"og:site_name\" content=\"Martes Neol\u00f3gico\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-12T05:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T08:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2021\/01\/trap_350.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\"},\"headline\":\"trap m. y adj.\",\"datePublished\":\"2021-01-12T05:00:41+00:00\",\"dateModified\":\"2025-08-01T08:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/\"},\"wordCount\":897,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"articleSection\":[\"ingl\u00e9s\",\"m\u00fasica\",\"pr\u00e9stamo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/\",\"name\":\"CVC. Trap | Martes Neol\u00f3gico\",\"isPartOf\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\"},\"datePublished\":\"2021-01-12T05:00:41+00:00\",\"dateModified\":\"2025-08-01T08:03:35+00:00\",\"description\":\"Art\u00edculo sobre el neologismo \u00abtrap\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.\",\"breadcrumb\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"trap m. y adj.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"name\":\"Martes Neol\u00f3gico\",\"description\":\"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario\",\"publisher\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization\",\"name\":\"Martes Neol\u00f3gico\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"contentUrl\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png\",\"width\":300,\"height\":100,\"caption\":\"Martes Neol\u00f3gico\"},\"image\":{\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CVC. Trap | Martes Neol\u00f3gico","description":"Art\u00edculo sobre el neologismo \u00abtrap\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/","og_locale":"es_ES","og_type":"article","og_title":"CVC. Trap | Martes Neol\u00f3gico","og_description":"Art\u00edculo sobre el neologismo \u00abtrap\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","og_url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/","og_site_name":"Martes Neol\u00f3gico","article_published_time":"2021-01-12T05:00:41+00:00","article_modified_time":"2025-08-01T08:03:35+00:00","og_image":[{"width":750,"height":350,"url":"http:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2021\/01\/trap_350.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#article","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/"},"author":{"name":"admin","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47"},"headline":"trap m. y adj.","datePublished":"2021-01-12T05:00:41+00:00","dateModified":"2025-08-01T08:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/"},"wordCount":897,"commentCount":0,"publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"articleSection":["ingl\u00e9s","m\u00fasica","pr\u00e9stamo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/","name":"CVC. Trap | Martes Neol\u00f3gico","isPartOf":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website"},"datePublished":"2021-01-12T05:00:41+00:00","dateModified":"2025-08-01T08:03:35+00:00","description":"Art\u00edculo sobre el neologismo \u00abtrap\u00bb, dentro del blog Martes Neol\u00f3gico del Centro Virtual Cervantes.","breadcrumb":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/trap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/"},{"@type":"ListItem","position":2,"name":"trap m. y adj."}]},{"@type":"WebSite","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#website","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","name":"Martes Neol\u00f3gico","description":"Cada martes, una palabra nueva que podr\u00eda estar en el diccionario","publisher":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#organization","name":"Martes Neol\u00f3gico","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/","url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","contentUrl":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-content\/uploads\/sites\/2\/2025\/10\/logo-martes-neologico-10-anos.png","width":300,"height":100,"caption":"Martes Neol\u00f3gico"},"image":{"@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/7e2fd26f886f53b1b2e81721d23acc47","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4b6a365b64e607f3d2ecd9620a7675a?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/6920"}],"collection":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/comments?post=6920"}],"version-history":[{"count":10,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/6920\/revisions"}],"predecessor-version":[{"id":13978,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/posts\/6920\/revisions\/13978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media\/6944"}],"wp:attachment":[{"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/media?parent=6920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/categories?post=6920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogscvc.cervantes.es\/martes-neologico\/wp-json\/wp\/v2\/tags?post=6920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}